{"id":510,"date":"2010-10-11T14:03:51","date_gmt":"2010-10-11T13:03:51","guid":{"rendered":"http:\/\/www.atelier-modern-art.at\/weblog\/?p=510"},"modified":"2010-10-11T14:11:24","modified_gmt":"2010-10-11T13:11:24","slug":"kurs","status":"publish","type":"post","link":"https:\/\/www.atelier-modern-art.at\/weblog\/kurs\/","title":{"rendered":"Kurs"},"content":{"rendered":"<p>Zwischendurch ein kurzer Bericht \u00fcber den kleinen Airbrush &amp; Acryl Kurs, denn ich so nebenbei leite.<\/p>\n<p>Martin, Raphael und Irene. Alle drei sehr begabte Teilnehmer, die mit beispielloser Motivation und viel Spa\u00df an die Sache herangehen.<\/p>\n<p><strong>[galobj viewid=14]<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zwischendurch ein kurzer Bericht \u00fcber den kleinen Airbrush &amp; Acryl Kurs, denn ich so nebenbei leite. Martin, Raphael und Irene. Alle drei sehr begabte Teilnehmer, die mit beispielloser Motivation und viel Spa\u00df an die Sache herangehen. [galobj viewid=14]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[138],"class_list":["post-510","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-allgemein","entry"],"_links":{"self":[{"href":"https:\/\/www.atelier-modern-art.at\/weblog\/wp-json\/wp\/v2\/posts\/510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atelier-modern-art.at\/weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.atelier-modern-art.at\/weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.atelier-modern-art.at\/weblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.atelier-modern-art.at\/weblog\/wp-json\/wp\/v2\/comments?post=510"}],"version-history":[{"count":4,"href":"https:\/\/www.atelier-modern-art.at\/weblog\/wp-json\/wp\/v2\/posts\/510\/revisions"}],"predecessor-version":[{"id":515,"href":"https:\/\/www.atelier-modern-art.at\/weblog\/wp-json\/wp\/v2\/posts\/510\/revisions\/515"}],"wp:attachment":[{"href":"https:\/\/www.atelier-modern-art.at\/weblog\/wp-json\/wp\/v2\/media?parent=510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.atelier-modern-art.at\/weblog\/wp-json\/wp\/v2\/categories?post=510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.atelier-modern-art.at\/weblog\/wp-json\/wp\/v2\/tags?post=510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}